{"id":1369,"date":"2024-06-27T17:07:54","date_gmt":"2024-06-27T17:07:54","guid":{"rendered":"https:\/\/ayatest.hddlife.com\/?page_id=1369"},"modified":"2025-06-25T11:02:03","modified_gmt":"2025-06-25T11:02:03","slug":"hddlife-support","status":"publish","type":"page","link":"https:\/\/hddlife.com\/de\/hddlife-support\/","title":{"rendered":"HDDlife support"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-7960302b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-622f57e2\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-50de8e98\"><h1 class=\"uagb-heading-text\">HDDLife-Unterst\u00fctzung<\/h1><\/div>\n\n\n\n<p>Wir m\u00f6chten, dass Ihre Frage so schnell wie m\u00f6glich an den richtigen Techniker weitergeleitet und beantwortet wird. Um uns dabei zu helfen, f\u00fcllen Sie bitte das nachstehende Formular aus. Geben Sie alle Details an, die Sie f\u00fcr hilfreich halten. Wir freuen uns \u00fcber jeden Vorschlag, wie wir unsere Software verbessern k\u00f6nnen.<\/p>\n\n\n\n<p>Oder Sie k\u00f6nnen unser Helpdesk-System hier nutzen:&nbsp;<a href=\"https:\/\/hddlife.com\/de\/support\/\">https:\/\/hddlife.com\/support<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size\">Wir sch\u00e4tzen Ihre Privatsph\u00e4re!<br>Ihre E-Mail-Adresse wird niemals in eine Mailing-Liste aufgenommen oder f\u00fcr andere Zwecke verwendet als f\u00fcr den Erhalt einer Antwort direkt von unseren Mitarbeitern.<\/p>\n\n\n\n<script src=\"https:\/\/desk.zoho.com\/portal\/api\/feedbackwidget\/1149410000000368604?orgId=891314976&#038;displayType=embeded\"><\/script>\n<div id=\"zsfeedbackwidgetdiv\"><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>HDDLife support We want to get your question to the right technician and answer it as quickly as possible. To help us do this, please fill out the form below. Include any details that you think would be helpful. We appreciate any suggestions on how we can improve our software. Or you can use our [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1369","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1750849400:1"],"_uag_custom_page_level_css":[""],"ast-site-content-layout":["default"],"theme-transparent-header-meta":[""],"adv-header-id-meta":[""],"stick-header-meta":[""],"astra-migrate-meta-layouts":["set"],"footnotes":[""],"_edit_last":["1"],"stackable_optimized_css":[""],"stackable_optimized_css_raw":["a:0:{}"],"site-post-title":["disabled"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_wpml_word_count":["{\"total\":95,\"to_translate\":{\"fr\":95,\"de\":95,\"it\":95}}"],"rank_math_seo_score":["70"],"rank_math_focus_keyword":["hddlife support"],"rank_math_description":["HDDLife Support: Submit questions, troubleshoot drive issues, and get expert assistance. Access guides, FAQs, and direct help for HDD\/SSD health monitoring and software optimization."],"inline_featured_image":[""],"site-sidebar-layout":["default"],"site-content-layout":[""],"site-content-style":["default"],"site-sidebar-style":["default"],"ast-global-header-display":[""],"ast-banner-title-visibility":[""],"ast-main-header-display":[""],"ast-hfb-above-header-display":[""],"ast-hfb-below-header-display":[""],"ast-hfb-mobile-header-display":[""],"ast-breadcrumbs-content":[""],"ast-featured-img":[""],"footer-sml-layout":[""],"header-above-stick-meta":[""],"header-main-stick-meta":[""],"header-below-stick-meta":[""],"ast-page-background-enabled":["default"],"ast-page-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:0:\"\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"ast-content-background-meta":["a:3:{s:7:\"desktop\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"tablet\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}s:6:\"mobile\";a:12:{s:16:\"background-color\";s:25:\"var(--ast-global-color-5)\";s:16:\"background-image\";s:0:\"\";s:17:\"background-repeat\";s:6:\"repeat\";s:19:\"background-position\";s:13:\"center center\";s:15:\"background-size\";s:4:\"auto\";s:21:\"background-attachment\";s:6:\"scroll\";s:15:\"background-type\";s:0:\"\";s:16:\"background-media\";s:0:\"\";s:12:\"overlay-type\";s:0:\"\";s:13:\"overlay-color\";s:0:\"\";s:15:\"overlay-opacity\";s:0:\"\";s:16:\"overlay-gradient\";s:0:\"\";}}"],"litespeed_vpi_list":["a:1:{i:0;s:37:\"cropped-hddlife_logo_140-1-120x39.png\";}"],"litespeed_vpi_list_mobile":["a:2:{i:0;s:37:\"cropped-hddlife_logo_140-1-120x39.png\";i:1;s:16:\"hddlife_logo.png\";}"],"_uag_css_file_name":["uag-css-1369.css"],"_uag_js_file_name":["uag-js-1369.js"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:34343:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-container.uagb-block-7960302b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7960302b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7960302b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7960302b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7960302b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7960302b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7960302b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 10px;}.wp-block-uagb-container.uagb-block-7960302b{box-shadow: 0px 0px   #00000070 ;padding-top: -50px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 0px;column-gap: 10px;}.wp-block-uagb-container.uagb-block-622f57e2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-622f57e2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-622f57e2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-622f57e2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-622f57e2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-622f57e2{max-width: 90%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-622f57e2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 16px;column-gap: 10px;}.wp-block-uagb-container.uagb-block-622f57e2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 16px;column-gap: 10px;}.wp-block-uagb-advanced-heading.uagb-block-50de8e98.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-50de8e98.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-50de8e98.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-50de8e98.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7960302b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7960302b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7960302b{padding-top: -50px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-622f57e2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-622f57e2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-622f57e2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-7960302b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7960302b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7960302b{padding-top: -50px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-622f57e2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-622f57e2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-622f57e2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\ufeff.uagb-forms__outer-wrap .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-input::placeholder,.uagb-forms__outer-wrap .uagb-forms-input-label,.uagb-forms__outer-wrap .uagb-forms-main-submit-button,.uagb-forms__outer-wrap .uagb-forms-success-message,.uagb-forms__outer-wrap .uagb-forms-failed-message{-webkit-transition-property:color,background-color,border-color;-moz-transition-property:color,background-color,border-color;-o-transition-property:color,background-color,border-color;transition-property:color,background-color,border-color;-webkit-transition-duration:.15s;-moz-transition-duration:.15s;-o-transition-duration:.15s;transition-duration:.15s}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]{min-height:0 !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-input::-webkit-input-placeholder,.uagb-forms__outer-wrap .uagb-forms-main-form input[type=text]::-webkit-input-placeholder{overflow:unset}.uagb-forms__outer-wrap .uagb-forms-main-form input:not([type=checkbox]):not([type=radio]):not([type=file]),.uagb-forms__outer-wrap .uagb-forms-main-form textarea,.uagb-forms__outer-wrap .uagb-forms-main-form select{width:100%;box-sizing:border-box}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-checkbox-wrap .uagb-form-checkbox-option input.uagb-inner-input-view{width:33%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-wrap .uagb-forms-phone-input{width:75% !important}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%;justify-content:space-between}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%;margin-right:5px}.uagb-forms__outer-wrap .uagb-forms-main-form .required::after{color:red;content:\" *\"}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-form-hidden-data{display:none}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-main-submit-button-wrap .uagb-forms-main-submit-button.wp-block-button__link{width:auto}.uagb-forms__outer-wrap .uagb-forms-submit-message-hide{display:none}.uagb-forms__outer-wrap .uagb-forms-success-message{padding:20px 20px}.uagb-forms__outer-wrap .uagb-forms-failed-message{padding:20px 20px}.uagb-forms__outer-wrap span.components-spinner{float:none}.uagb-forms__outer-wrap .uagb-forms-input.uagb-form-phone-country{background-color:#fff}.uagb-forms__outer-wrap .uag-col-2-wrap{display:grid;grid-template-columns:1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-3-wrap{display:grid;grid-template-columns:1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uag-col-4-wrap{display:grid;grid-template-columns:1fr 1fr 1fr 1fr;column-gap:15px}.uagb-forms__outer-wrap .uagb-switch{position:relative;display:inline-block;width:50px;height:25px}.uagb-forms__outer-wrap .uagb-switch input{width:0;height:0;opacity:0}.uagb-forms__outer-wrap .uagb-slider{position:absolute;top:0;right:0;bottom:0;left:0;background-color:#fff;cursor:pointer;transition:.4s;-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch .uagb-slider::before{position:absolute;width:20px;height:20px;background-color:#000;transition:.4s;content:\"\";-webkit-transition:.4s}.uagb-forms__outer-wrap .uagb-switch input:checked+.uagb-slider::before{background-color:#fff}.uagb-forms__outer-wrap .uagb-slider.round::before{border-radius:50% !important}.uagb-forms-select-box,.uagb-form-phone-country,.uagb-forms-phone-wrap .uagb-forms-phone-input{height:auto;-webkit-appearance:none;appearance:none}.uagb-forms-radio-wrap input[type=radio]:checked+label::before{line-height:1.2;content:\" \"}.uagb-forms-radio-wrap input[type=radio]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\"\"}.uagb-forms-radio-wrap input[type=radio].round+label::before{border-radius:100% !important}select::after,select::before{padding:10px}.uagb-forms-radio-wrap input[type=radio],.uagb-forms-checkbox-wrap input[type=checkbox],.uagb-forms-accept-wrap input[type=checkbox]{opacity:0}.uagb-forms-checkbox-wrap input[type=checkbox]:checked+label::before,.uagb-forms-accept-wrap input[type=checkbox]:checked+label::before{line-height:1.2;content:\"\u2714\"}.uagb-forms-checkbox-wrap input[type=checkbox]+label::before,.uagb-forms-accept-wrap input[type=checkbox]+label::before{display:inline-block;vertical-align:middle;margin-right:10px;margin-bottom:5px;box-sizing:content-box;text-align:center;line-height:1.2;content:\" \"}@media only screen and (max-width: 767px){.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex{display:flex;width:100%}.uagb-forms__outer-wrap .uagb-forms-main-form .uagb-forms-phone-flex .uagb-form-phone-country{width:25%}}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-20 .uagb-forms-main-form{column-gap:20px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-15 .uagb-forms-main-form{column-gap:15px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-10 .uagb-forms-main-form{column-gap:10px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-column-gap-5 .uagb-forms-main-form{column-gap:5px}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-desk-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-flex-start .uagb-forms-main-form{align-items:flex-start}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-align-item-center .uagb-forms-main-form{align-items:center}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form{display:flex;flex-wrap:wrap;margin:0 -5px;position:relative;text-align:left}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-desk-width-80{width:80%}@media(min-width: 768px)and (max-width: 1024px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-tablet-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-tablet-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}@media(max-width: 767px){.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-20{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-25{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-33{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-40{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-50{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-60{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-66{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-75{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-80{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-100{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field .uagb-forms-main-form .uagb-forms-field-mobile-width-unset{width:auto}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-20 .uagb-forms-main-submit-button-wrap{width:20%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-25 .uagb-forms-main-submit-button-wrap{width:25%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-33 .uagb-forms-main-submit-button-wrap{width:33.33%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-40 .uagb-forms-main-submit-button-wrap{width:40%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-50 .uagb-forms-main-submit-button-wrap{width:50%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-60 .uagb-forms-main-submit-button-wrap{width:60%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-66 .uagb-forms-main-submit-button-wrap{width:66.66%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-75 .uagb-forms-main-submit-button-wrap{width:75%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-80 .uagb-forms-main-submit-button-wrap{width:80%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-100 .uagb-forms-main-submit-button-wrap{width:100%}.wp-block-uagb-forms.uagb-forms-inline-field.uagb-forms-button-mobile-width-unset .uagb-forms-main-submit-button-wrap{width:auto}}.uagb-block-d276cdda.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d276cdda .uagb-forms-main-form textarea{text-align: left;}.uagb-block-d276cdda .uagb-forms-input{text-align: left;}.uagb-block-d276cdda .uagb-forms-input-label{display: none;text-align: left;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-field-set{margin-bottom: 20px;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;margin-bottom: 10px;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input:focus{outline:  none !important;background-color: #fafafa !important;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input:focus::placeholder{color: #797979 !important;}.uagb-block-d276cdda .uagb-forms-field-set:hover .uagb-forms-input{background-color: #fafafa;}.uagb-block-d276cdda .uagb-forms-field-set:hover .uagb-forms-input::placeholder{color: #797979;}.uagb-block-d276cdda .uagb-slider.round{border-radius: 20px !important;}.uagb-block-d276cdda .uagb-form-phone-country{background: url(data:image\/svg+xml;base64,PHN2ZyB2aWV3Qm94PSIwIDAgNTEyIDUxMiIgd2lkdGg9JzE4cHgnIGhlaWdodD0nMThweCcgeG1sOnNwYWNlPSJwcmVzZXJ2ZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIiBlbmFibGUtYmFja2dyb3VuZD0ibmV3IDAgMCA1MTIgNTEyIj48cGF0aCBkPSJtMzk2LjYgMTYwIDE5LjQgMjAuN0wyNTYgMzUyIDk2IDE4MC43bDE5LjMtMjAuN0wyNTYgMzEwLjV6IiBmaWxsPSIjMWQyMzI3IiBjbGFzcz0iZmlsbC0wMDAwMDAiPjwvcGF0aD48L3N2Zz4=) no-repeat;-moz-appearance: none !important;-webkit-appearance:  none !important;background-position:  top 50% right 12px;appearance: none !important;color: #797979;}.uagb-block-d276cdda .uagb-forms-field-set:hover .uagb-form-phone-country{color: #797979;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{text-align: left;}.uagb-block-d276cdda .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-d276cdda .uagb-forms-radio-wrap input[type=radio] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-d276cdda .uagb-slider{background-color: #ffffff;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider:before{height: 20px;width: 20px;top: 3px;bottom: 3px;left: 3px;background-color: #1e1e1e;border-radius: 3px 3px 3px 3px;}.uagb-block-d276cdda .uagb-switch input:checked + .uagb-slider{background-color: #017cba;}.uagb-block-d276cdda .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);background-color: #ffffff;}.uagb-block-d276cdda .uagb-switch input:focus + .uagb-slider{box-shadow: 0 0 1px#017cba;}.uagb-block-d276cdda .uagb-forms-accept-wrap input[type=checkbox] + label:before{background-color: #ffffff;width: 15px;height: 15px;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 3px;border-top-right-radius: 3px;border-bottom-left-radius: 3px;border-bottom-right-radius: 3px;border-color: #BDBDBD;border-style: solid;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input{background-color: #fafafa;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #dddddd;border-style: solid;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input.uagb-form-phone-country{padding-top: 11px;padding-bottom: 11px;padding-left: 12px;padding-right: 12px;}.uagb-block-d276cdda .uagb-forms-input::placeholder{color: #797979;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-input{font-weight: 400;font-size: 18px;line-height: 1em;padding-top: 12px;padding-bottom: 12px;padding-left: 12px;padding-right: 12px;}.uagb-block-d276cdda .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-radio-wrap input[type=radio]:checked + label:before{background-color: #ffffff;box-shadow: inset 0 0 0 4px #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{color: #ffffff;background-color: #017cba;font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-input::placeholder{font-weight: 400;font-size: 18px;line-height: 1em;}@media only screen and (max-width: 976px) {.uagb-block-d276cdda.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-d276cdda .uagb-slider.round{border-radius: 20px !important;}.uagb-block-d276cdda .uagb-form-phone-country{background-position: top 50% right 12px;padding-right: 30px;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #dddddd;}.uagb-block-d276cdda .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-d276cdda .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}@media only screen and (max-width: 767px) {.uagb-block-d276cdda.uagb-forms__outer-wrap{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input-label{font-size: 15px;}.uagb-block-d276cdda .uagb-slider.round{border-radius: 20px !important;}.uagb-block-d276cdda .uagb-form-phone-country{background-position: top 50% right 6px;padding-right: 30px;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-main-submit-button-wrap{display: grid;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-checkbox-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-radio-wrap input[type=radio] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form  .uagb-forms-accept-wrap input[type=checkbox] + label:before{border-style: solid;border-color: #BDBDBD;}.uagb-block-d276cdda .uagb-forms-main-form .uagb-forms-input{border-style: solid;border-color: #dddddd;}.uagb-block-d276cdda .uagb-switch input:checked + .uagb-slider:before{transform: translateX(30px);}.uagb-block-d276cdda .uagb-forms-checkbox-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-radio-wrap input[type=radio]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-accept-wrap input[type=checkbox]:checked + label:before{font-size: calc(15px \/ 1.2);}.uagb-block-d276cdda .uagb-forms-main-form .uagb-switch{height: calc(1px + 1px + 26px);width: calc(1px + 1px + 56px);}.uagb-block-d276cdda .uagb-forms-main-form .uagb-slider:before{height: calc(20px + 0px);width: calc(20px + 0px);top: 3px;bottom: 3px;left: 3px;border-radius: 3px 3px 3px 3px;}}\";s:2:\"js\";s:586:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener(\"DOMContentLoaded\", function(){\n\tUAGBForms.init( {\"block_id\":\"d276cdda\",\"reCaptchaEnable\":false,\"reCaptchaType\":\"v2\",\"reCaptchaSiteKeyV2\":\"\",\"reCaptchaSiteKeyV3\":\"\",\"afterSubmitToEmail\":\"abc@gmail.com\",\"afterSubmitCcEmail\":\"\",\"afterSubmitBccEmail\":\"\",\"afterSubmitEmailSubject\":\"Formularu00fcbermittlung\",\"sendAfterSubmitEmail\":true,\"confirmationType\":\"message\",\"hidereCaptchaBatch\":false,\"captchaMessage\":\"Please fill up the above captcha.\",\"confirmationUrl\":\"\"}, '.uagb-block-d276cdda', 1369 );\n});\n });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:2;s:21:\"uagb\/advanced-heading\";i:3;s:14:\"core\/paragraph\";i:4;s:9:\"core\/html\";i:5;s:11:\"core\/search\";i:6;s:10:\"core\/group\";i:7;s:12:\"core\/heading\";i:8;s:17:\"core\/latest-posts\";i:9;s:20:\"core\/latest-comments\";i:10;s:13:\"core\/archives\";i:11;s:15:\"core\/categories\";i:12;s:10:\"uagb\/forms\";i:13;s:16:\"uagb\/forms-email\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778674961\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/hddlife.com\/de\/author\/ayaadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"HDDLife support We want to get your question to the right technician and answer it as quickly as possible. To help us do this, please fill out the form below. Include any details that you think would be helpful. We appreciate any suggestions on how we can improve our software. Or you can use our&hellip;","_links":{"self":[{"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/pages\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":0,"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/pages\/1369\/revisions"}],"wp:attachment":[{"href":"https:\/\/hddlife.com\/de\/wp-json\/wp\/v2\/media?parent=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}